{"id":4711,"date":"2026-04-15T17:21:05","date_gmt":"2026-04-15T17:21:05","guid":{"rendered":"https:\/\/vidapublicarevista.com\/?p=4711"},"modified":"2026-04-15T17:22:21","modified_gmt":"2026-04-15T17:22:21","slug":"de-veras-seria-tan-malo","status":"publish","type":"post","link":"https:\/\/vidapublicarevista.com\/index.php\/2026\/04\/15\/de-veras-seria-tan-malo\/","title":{"rendered":"\u00bfDe veras ser\u00eda tan malo?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Culiac\u00e1n, Sinaloa, 15 de abril 2026. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el\u00a0acuerdo\u00a0comercial entre M\u00e9xico, Estados Unidos y Canad\u00e1 (TLC, TLCAN, TMEC) se\u00a0busca, <strong>al menos en lo declarativo, promover el desarrollo econ\u00f3mico del pa\u00eds y la inversi\u00f3n extranjera<\/strong>.\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, a m\u00e1s de 30 a\u00f1os de su entrada en vigor, la red&nbsp;integrada&nbsp;por&nbsp;colectivos y organizaciones&nbsp;de&nbsp;18 estados mexicanos&nbsp;denunci\u00f3 que&nbsp;<strong>sus comunidades fueron enga\u00f1adas&nbsp;\u201ccon la promesa de empleos y buenos salarios\u201d<\/strong>&nbsp;y hoy&nbsp;padecen&nbsp;<strong>da\u00f1inas consecuencias del TLCAN.&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esa red (Renacer) afirma que los llevados y tra\u00eddos tratados&nbsp;de libre comercio&nbsp;han causado&nbsp;\u201cla violenta devastaci\u00f3n de nuestro entorno natural, las graves enfermedades&nbsp;cr\u00f3nico-degenerativas y muertes en familias de comunidades rurales\u201d.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa llegada del neoliberalismo fue particularmente lesiva porque torci\u00f3 la redacci\u00f3n de leyes y normas que <strong>debieron proteger la salud y el medio ambiente<\/strong>, volvi\u00e9ndolas permisivas, para que el&nbsp;pa\u00eds resultara atractivo a los negocios estadunidenses, canadienses y europeos\u201d, expresa la red Renacer.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfY QUI\u00c9NES SON LOS GANANCIOSOS?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el primer TLC <strong>la divisa fue establecer una correspondencia con ciertas condiciones de entrada: costos de producci\u00f3n baratos (para las grandes empresas);<\/strong> mercados abiertos, exenciones impositivas, tratos privilegiados y ganancias muy altas con los diferenciales. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde finales del siglo pasado, Eduardo Galeano advirti\u00f3 que \u201cel tratado maximiz\u00f3 las oportunidades de utilizaci\u00f3n de los recursos ofrecidos por las ventajas comparativas\u201d y <strong>\u00bfcu\u00e1les son esas ventajas?<\/strong> Los bajos salarios, la permisibilidad para la explotaci\u00f3n de los recursos naturales, tierra y agua, como se ha visto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>PARA TENER EN CUENTA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que ha prevalecido en los menjurjes del mercado es <strong>el inter\u00e9s, la ganancia de las empresas transnacionales<\/strong>, con el agregado de que se recurre a \u201cimportaciones desleales\u201d y diversas trampas para seguir vendiendo a su arbitrio y ganar cada vez m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con frecuencia no se dice, o se margina, pero las protestas de productores agr\u00edcolas, el paro nacional, los bloqueos a carreteras, las protestas en general est\u00e1n relacionadas con lo arriba se\u00f1alado.<strong>La crisis del campo tiene referentes<\/strong> que apuntan a las condiciones en que se negocia el TLC o TMEC, y a los intereses que prevalecen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>MITIFICACI\u00d3N CONVENIENTE<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero se ha mitificado el tratado <strong>como si fuera la panacea del crecimiento y el desarrollo<\/strong>, lo que est\u00e1 muy lejos de ser as\u00ed. <strong>Lo que hay son simples paliativos<\/strong> que pierden su valor en el corto plazo, mientras que los da\u00f1os al sector agropecuario, entre otros, son de larga data.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De ah\u00ed que la pregunta que encabeza esta columna debe ser respondida con honradez por el gobierno y el sector privado exportador (uno de los que relativamente ganan): <strong>\u00bfde veras ser\u00eda una tragedia si no hay TMEC?&nbsp;&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfY qu\u00e9 si los grandes ricos del pa\u00eds invirtieran sus fortunas en el sector productivo en lugar de mandar sus capitales a los para\u00edsos fiscales?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPor qu\u00e9 no se privilegia el desarrollo interno en lugar de ganar intereses bancarios o apostar a la especulaci\u00f3n bolsera?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como dir\u00eda Dylan: <strong>la respuesta est\u00e1 en el viento<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EN EL TINTERO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Me vale el mundial, pero amenazar con boicotearlo \u00bfsi no es chantaje qu\u00e9 es?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>La codicia de los concesionarios de estaciones de combustible<\/strong> se sigue imponiendo, d\u00edgase lo que se diga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; \u00bfSubsidios para los paros y tomas de casetas? Dijo Sheinbaum que ya no se dar\u00edan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-No se sabe qu\u00e9 seguir\u00e1 con <strong>la locura del delincuente Trump<\/strong>, mientras el mundo siga pasmado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; \u00bfCultura laboral? La enorme mayor\u00eda de las empresas incumplen con los horarios que ellas mismas se han puesto y con los compromisos de trabajo. Los talleres mec\u00e1nicos se llevan la oprobiosa medalla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfPor qu\u00e9 no se privilegia el desarrollo interno en lugar de ganar intereses bancarios?<\/p>\n","protected":false},"author":19,"featured_media":4712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[2,7],"tags":[],"class_list":["post-4711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","category-opinion"],"aioseo_notices":[],"views":23,"_links":{"self":[{"href":"https:\/\/vidapublicarevista.com\/index.php\/wp-json\/wp\/v2\/posts\/4711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vidapublicarevista.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vidapublicarevista.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vidapublicarevista.com\/index.php\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/vidapublicarevista.com\/index.php\/wp-json\/wp\/v2\/comments?post=4711"}],"version-history":[{"count":1,"href":"https:\/\/vidapublicarevista.com\/index.php\/wp-json\/wp\/v2\/posts\/4711\/revisions"}],"predecessor-version":[{"id":4713,"href":"https:\/\/vidapublicarevista.com\/index.php\/wp-json\/wp\/v2\/posts\/4711\/revisions\/4713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vidapublicarevista.com\/index.php\/wp-json\/wp\/v2\/media\/4712"}],"wp:attachment":[{"href":"https:\/\/vidapublicarevista.com\/index.php\/wp-json\/wp\/v2\/media?parent=4711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vidapublicarevista.com\/index.php\/wp-json\/wp\/v2\/categories?post=4711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vidapublicarevista.com\/index.php\/wp-json\/wp\/v2\/tags?post=4711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}